{"id":1706,"date":"2023-03-31T19:35:54","date_gmt":"2023-04-01T01:35:54","guid":{"rendered":"https:\/\/www.labofine.com\/?p=1706"},"modified":"2023-03-31T19:35:54","modified_gmt":"2023-04-01T01:35:54","slug":"dietary-supplement-testing-faq","status":"publish","type":"post","link":"https:\/\/www.labofine.com\/fr\/blog\/dietary-supplement-testing-faq\/","title":{"rendered":"FAQ sur les tests de compl\u00e9ments alimentaires"},"content":{"rendered":"<p><a href=\"https:\/\/www.labofine.com\/fr\/dietary-supplement-testing\/\">Les tests de compl\u00e9ments alimentaires<\/a> nous vous aiderons \u00e0 tout d\u00e9terminer, de \nl'efficacit\u00e9 de votre produit \u00e0 la dur\u00e9e de conservation. Dans l'article d'aujourd'hui, nous \nallons discuter de quatre des questions les plus fr\u00e9quemment pos\u00e9es sur nos tests de \ncompl\u00e9ments alimentaires. Lisez la suite pour en savoir plus <a href=\"https:\/\/www.labofine.com\/fr\/\">Labofine<\/a>, we\u2019ll help you determine everything from the efficacy of your product to the shelf life.<br \/>\nIn today\u2019s article, we are going to discuss four of the most commonly asked questions about our dietary supplement testing. Read on to learn more. <\/p>\n<p><div class=\"row\"><div class=\"col-sm-6\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1.jpg\" alt=\"\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-1711\" srcset=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1.jpg 1080w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1-300x300.jpg 300w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1-1024x1024.jpg 1024w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1-150x150.jpg 150w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-1-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><\/p><\/div><div class=\"col-sm-6\">\n<h3>Qu'est-ce que le test des compl\u00e9ments alimentaires ?<\/h3>\n<p>Les tests de compl\u00e9ments alimentaires sont un processus de v\u00e9rification de l'innocuit\u00e9, \nde la qualit\u00e9 et de l'efficacit\u00e9 des compl\u00e9ments alimentaires. Ce processus implique \nl'analyse des mati\u00e8res premi\u00e8res et des produits finis \u00e0 la recherche de contaminants, \nd'additifs et d'ingr\u00e9dients actifs. Il s'agit \u00e9galement de tester la stabilit\u00e9, la dur\u00e9e de \nconservation et les all\u00e9gations faites sur l'emballage. Selon le produit ou le fabricant, il \npeut y avoir des tests ou des exigences suppl\u00e9mentaires pour les tests de compl\u00e9ments \nalimentaires.<\/p>\n<p><\/p><\/div><\/div><div class=\"row\"><div class=\"col-sm-6\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2.jpg\" alt=\"\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-1710\" srcset=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2.jpg 1080w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2-300x300.jpg 300w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2-1024x1024.jpg 1024w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2-150x150.jpg 150w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-2-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><\/p><\/div><div class=\"col-sm-6\">\n<h3>Comment les compl\u00e9ments alimentaires sont-ils test\u00e9s ?<\/h3>\n<p>Les tests de compl\u00e9ments alimentaires peuvent impliquer une vari\u00e9t\u00e9 de m\u00e9thodes \ndiff\u00e9rentes. Ces m\u00e9thodes peuvent inclure l'utilisation de la chromatographie liquide \u00e0 \nhaute performance (HPLC), de la chromatographie en phase gazeuse (GC) et de la \nspectrom\u00e9trie de masse (MS). Ces m\u00e9thodes permettent de d\u00e9tecter les contaminants, les \nadult\u00e9rants et d'autres substances qui peuvent avoir un impact sur la s\u00e9curit\u00e9 et la qualit\u00e9 \nd'un suppl\u00e9ment. D'autres tests, tels que des tests de stabilit\u00e9, peuvent \u00e9galement \u00eatre \nutilis\u00e9s pour s'assurer que le suppl\u00e9ment conserve son efficacit\u00e9 dans le temps<\/p>\n<p><\/p><\/div><\/div><div class=\"row\"><div class=\"col-sm-6\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3.jpg\" alt=\"\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-1709\" srcset=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3.jpg 1080w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3-300x300.jpg 300w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3-1024x1024.jpg 1024w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3-150x150.jpg 150w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-3-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><\/p><\/div><div class=\"col-sm-6\">\n<h3>Qui est responsable des tests de compl\u00e9ments alimentaires ?<\/h3>\n<p>Les tests des compl\u00e9ments alimentaires sont g\u00e9n\u00e9ralement de la responsabilit\u00e9 du \nfabricant. Les fabricants sont responsables de s'assurer que les produits qu'ils fabriquent \nsont s\u00fbrs et r\u00e9pondent \u00e0 toutes les r\u00e9glementations applicables. Sant\u00e9 Canada et la Food \nand Drug Administration (FDA) des \u00c9tats-Unis sont \u00e9galement responsables de la \nsurveillance de l'innocuit\u00e9 et de la qualit\u00e9 des suppl\u00e9ments alimentaires, et ils peuvent \nexiger des tests ou des documents suppl\u00e9mentaires de la part des fabricants.<\/p>\n<p><\/p><\/div><\/div><div class=\"row\"><div class=\"col-sm-6\">\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4.jpg\" alt=\"\" width=\"1080\" height=\"1080\" class=\"alignnone size-full wp-image-1708\" srcset=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4.jpg 1080w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4-300x300.jpg 300w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4-1024x1024.jpg 1024w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4-150x150.jpg 150w, https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/Dietary-Supplement-Testing-FAQ-Image-4-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><\/p><\/div><div class=\"col-sm-6\">\n<h3>Quels sont les types de tests de compl\u00e9ments alimentaires disponibles ?<\/h3>\n<p>Les types de tests de compl\u00e9ments alimentaires qui peuvent \u00eatre effectu\u00e9s pour \u00e9valuer \nla qualit\u00e9 et l'innocuit\u00e9 d'un suppl\u00e9ment comprennent :<\/p>\n<ul>\n<li><strong>Test d'identit\u00e9 des ingr\u00e9dients :<\/strong> Ce test est utilis\u00e9 pour v\u00e9rifier les ingr\u00e9dients \npr\u00e9sents dans le suppl\u00e9ment.<\/li>\n<li><strong>Test de puissance :<\/strong> Ce test est utilis\u00e9 pour mesurer la quantit\u00e9 de l'ingr\u00e9dient \nactif dans le produit.<\/li>\n<li>Test microbiologique : Ce test est utilis\u00e9 pour d\u00e9tecter la pr\u00e9sence de microorganismes, tels que des bact\u00e9ries et des champignons, dans le su<\/li>\n<li><strong>Test de m\u00e9taux lourds :<\/strong> Ce test est utilis\u00e9 pour d\u00e9tecter la pr\u00e9sence de m\u00e9taux lourds, tels que le plomb, le mercure et l'arsenic, dans le suppl\u00e9ment.<\/li>\n<li><strong>Test de puret\u00e9 :<\/strong> Ce test est utilis\u00e9 pour d\u00e9tecter la pr\u00e9sence d'impuret\u00e9s, telles \nque des pesticides, dans le suppl\u00e9ment.<\/li>\n<li><strong>Test de stabilit\u00e9 :<\/strong> Ce test est utilis\u00e9 pour d\u00e9terminer la dur\u00e9e de conservation du \nsuppl\u00e9ment.<\/li>\n<\/ul>\n<p><\/p><\/div><\/div><\/p>\n<h3>Test de compl\u00e9ments alimentaires \u00e0 Pointe-Claire<\/h3>\n<p>Que vous d\u00e9veloppiez un nouveau compl\u00e9ment alimentaire ou que vous mettiez \u00e0 jour la \nformule d'un compl\u00e9ment alimentaire actuel, Labofine est le Laboratoire d'analyse <a href=\"https:\/\/www.labofine.com\/fr\/dietary-supplement-testing\/\">des compl\u00e9ments alimentaires<\/a> sur lequel vous pouvez compter. <a href=\"https:\/\/www.labofine.com\/fr\/contact\/\">Contactez-nous<\/a> aujourd'hui <a href=\"https:\/\/www.labofine.com\/fr\/\">Pointe-Claire lab<\/a> pour en savoir plus. <\/p>\n<h2><a href=\"https:\/\/www.labofine.com\/fr\/contact\/\">Contactez-nous aujourd'hui<\/a><\/h2>","protected":false},"excerpt":{"rendered":"<p>Les tests de compl\u00e9ments alimentaires sont essentiels pour s'assurer que les suppl\u00e9ments \nfonctionnent comme ils le devraient et qu'ils sont sans danger pour le consommateur. \nAvec les tests de compl\u00e9ments alimentaires, nous vous aiderons \u00e0 tout d\u00e9terminer, de \nl'efficacit\u00e9 de votre produit \u00e0 la dur\u00e9e de conservation...<\/p>","protected":false},"author":12,"featured_media":1712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[39,67,69,68,70,71],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dietary Supplement Testing FAQ - Labofine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labofine.com\/fr\/blog\/dietary-supplement-testing-faq\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dietary Supplement Testing FAQ - Labofine\" \/>\n<meta property=\"og:description\" content=\"Dietary supplement testing is essential for ensuring supplements work the way they should and that they are safe for the consumer. With the dietary supplement testing at Labofine, we\u2019ll help you determine everything from the efficacy of your product to the shelf life. In today\u2019s article, we are going to discuss four of the most&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labofine.com\/fr\/blog\/dietary-supplement-testing-faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Labofine\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-01T01:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"madwire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"madwire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/\",\"url\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/\",\"name\":\"Dietary Supplement Testing FAQ - Labofine\",\"isPartOf\":{\"@id\":\"https:\/\/www.labofine.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg\",\"datePublished\":\"2023-04-01T01:35:54+00:00\",\"dateModified\":\"2023-04-01T01:35:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.labofine.com\/#\/schema\/person\/b1d5766db6b307e28c5f46e4130c3b63\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage\",\"url\":\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg\",\"contentUrl\":\"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.labofine.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dietary Supplement Testing FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.labofine.com\/#website\",\"url\":\"https:\/\/www.labofine.com\/\",\"name\":\"Labofine\",\"description\":\"| A Tentamus Company\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.labofine.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.labofine.com\/#\/schema\/person\/b1d5766db6b307e28c5f46e4130c3b63\",\"name\":\"madwire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.labofine.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6350e644bacb6eb096f94a4b6a56c7df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6350e644bacb6eb096f94a4b6a56c7df?s=96&d=mm&r=g\",\"caption\":\"madwire\"},\"url\":\"https:\/\/www.labofine.com\/fr\/author\/madwire\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dietary Supplement Testing FAQ - Labofine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labofine.com\/fr\/blog\/dietary-supplement-testing-faq\/","og_locale":"fr_CA","og_type":"article","og_title":"Dietary Supplement Testing FAQ - Labofine","og_description":"Dietary supplement testing is essential for ensuring supplements work the way they should and that they are safe for the consumer. With the dietary supplement testing at Labofine, we\u2019ll help you determine everything from the efficacy of your product to the shelf life. In today\u2019s article, we are going to discuss four of the most&hellip;","og_url":"https:\/\/www.labofine.com\/fr\/blog\/dietary-supplement-testing-faq\/","og_site_name":"Labofine","article_published_time":"2023-04-01T01:35:54+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg","type":"image\/jpeg"}],"author":"madwire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"madwire","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/","url":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/","name":"Dietary Supplement Testing FAQ - Labofine","isPartOf":{"@id":"https:\/\/www.labofine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage"},"image":{"@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg","datePublished":"2023-04-01T01:35:54+00:00","dateModified":"2023-04-01T01:35:54+00:00","author":{"@id":"https:\/\/www.labofine.com\/#\/schema\/person\/b1d5766db6b307e28c5f46e4130c3b63"},"breadcrumb":{"@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#primaryimage","url":"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg","contentUrl":"https:\/\/www.labofine.com\/wp-content\/uploads\/2023\/03\/C1107-Blog-Post-Dietary-Supplement-Testing-FAQ-Featured-Image.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.labofine.com\/blog\/dietary-supplement-testing-faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.labofine.com\/"},{"@type":"ListItem","position":2,"name":"Dietary Supplement Testing FAQ"}]},{"@type":"WebSite","@id":"https:\/\/www.labofine.com\/#website","url":"https:\/\/www.labofine.com\/","name":"Labofine","description":"| A Tentamus Company","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labofine.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.labofine.com\/#\/schema\/person\/b1d5766db6b307e28c5f46e4130c3b63","name":"madwire","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.labofine.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6350e644bacb6eb096f94a4b6a56c7df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6350e644bacb6eb096f94a4b6a56c7df?s=96&d=mm&r=g","caption":"madwire"},"url":"https:\/\/www.labofine.com\/fr\/author\/madwire\/"}]}},"_links":{"self":[{"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/posts\/1706"}],"collection":[{"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/comments?post=1706"}],"version-history":[{"count":2,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/posts\/1706\/revisions"}],"predecessor-version":[{"id":1713,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/posts\/1706\/revisions\/1713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/media\/1712"}],"wp:attachment":[{"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/media?parent=1706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/categories?post=1706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.labofine.com\/fr\/wp-json\/wp\/v2\/tags?post=1706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}